{"id":698,"date":"2021-06-30T09:14:23","date_gmt":"2021-06-30T09:14:23","guid":{"rendered":"https:\/\/www.arnwald.art\/?p=698"},"modified":"2024-02-28T17:51:26","modified_gmt":"2024-02-28T17:51:26","slug":"co-prod-2020","status":"publish","type":"post","link":"https:\/\/www.arnwald.ovh\/en\/co-prod-2020\/","title":{"rendered":"Comment quitter les GAFAM (2020)"},"content":{"rendered":"<div class=\"wp-block-image is-resized\">\n<figure class=\"alignleft size-large\"><a href=\"https:\/\/www.arnwald.ovh\/files\/2021\/07\/GAFA-time-is-ending.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"914\" height=\"1024\" src=\"https:\/\/www.arnwald.ovh\/files\/2021\/07\/GAFA-time-is-ending-914x1024.jpg\" alt=\"\" class=\"wp-image-721\" srcset=\"https:\/\/www.arnwald.ovh\/files\/2021\/07\/GAFA-time-is-ending-914x1024.jpg 914w, https:\/\/www.arnwald.ovh\/files\/2021\/07\/GAFA-time-is-ending-268x300.jpg 268w, https:\/\/www.arnwald.ovh\/files\/2021\/07\/GAFA-time-is-ending-768x861.jpg 768w, https:\/\/www.arnwald.ovh\/files\/2021\/07\/GAFA-time-is-ending-400x448.jpg 400w, https:\/\/www.arnwald.ovh\/files\/2021\/07\/GAFA-time-is-ending-600x673.jpg 600w, https:\/\/www.arnwald.ovh\/files\/2021\/07\/GAFA-time-is-ending.jpg 1142w\" sizes=\"auto, (max-width: 914px) 100vw, 914px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Facebook bloque l\u2019article que tu veux partager<br>Twitter le supprime<br>Google le dissimule<br>Youtube l\u2019interdit<br>Alors, le moment est venu de quitter les lieux&#8230;<\/h2>\n\n\n\n<p>Quand la libert\u00e9 dispara\u00eet, que le voile des dictatures se l\u00e8ve, que les masques s&#8217;abaissent laconiquement devant les yeux rest\u00e9s ouverts, la meilleure chose \u00e0 faire est de quitter les lieux. J&#8217;avais pass\u00e9 quelques d\u00e9cennies sur l&#8217;internet, je l&#8217;avais vu na\u00eetre, se transformer en ar\u00e8ne commerciale, en outil de propagande. J&#8217;ai quitt\u00e9 les GAFAM sans un regret. Je pouvais me le permettre, ma vie ne d\u00e9pendait pas d&#8217;eux.<br> il n&#8217;y pas de r\u00e9alit\u00e9 plus facile \u00e0 changer que la r\u00e9alit\u00e9 virtuelle, rien n&#8217;y est grav\u00e9 dans le marbre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Au commencement des ann\u00e9es 20<\/h2>\n\n\n\n<p>j&#8217;ai eu le privil\u00e8ge de participer au financement participatif du documentaire de <strong>Pierre Barn\u00e9rias<\/strong> : <strong>Hold Up<\/strong>, 1er opus d\u2019une trilogie. Hold On suivra, suivi de Hold Out.<br>S&#8217;expriment, entre autres, dans ce documentaire, deux prix nobels, une d\u00e9put\u00e9e, un ancien ministre, etc.<br>Censur\u00e9 en France mais sortit en salles au Qu\u00e9bec en 2021, Hold Up + est en visionnage gratuit sur :<br><a href=\"https:\/\/holdup-lefilm.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>https:\/\/holdup-lefilm.fr\/<\/strong><\/a><br><br>Pierre Barn\u00e9rias est \u00e9galement auteur d&#8217;autres documentaires tout aussi qualitatifs dont  :<br><strong>Thanatos :<\/strong> <a href=\"https:\/\/tprod.fr\/project\/thanatos-l-ultime-passage\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/tprod.fr\/project\/thanatos-l-ultime-passage\/<\/a> &#8211; qui explore la th\u00e9matique des Exp\u00e9riences de Mort Imminente (EMI) avec de nombreux t\u00e9moignages.<br><strong>M et le 3e secret : <\/strong><a href=\"https:\/\/tprod.fr\/project\/m-et-le-3eme-secret\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/tprod.fr\/project\/m-et-le-3eme-secret\/<\/a> &#8211; qui traite du 3e secret des r\u00e9v\u00e9lations de Fatima (1917)<\/p>\n\n\n\n<p><br><strong>l\u2019Empreinte<\/strong> &#8211; <a href=\"https:\/\/tprod.fr\/project\/lempreinte\/\" target=\"_blank\" rel=\"noopener\" title=\"https:\/\/tprod.fr\/project\/lempreinte\/\">https:\/\/tprod.fr\/project\/lempreinte\/<\/a>, raconte la travers\u00e9e de l\u2019Europe de Florian Gromet, courant pied nu, sans argent et sans papiers, un marathon par jour.<\/p>\n\n\n\n<p><br><strong>Miracles<\/strong> &#8211; <a href=\"https:\/\/miracles-lefilm.com\/\" target=\"_blank\" rel=\"noopener\" title=\"https:\/\/miracles-lefilm.com\/\">https:\/\/miracles-lefilm.com\/<\/a>, traite de 3 miracles, le linceul dTurin, Notre Dame de Guadalupe et, les \u00e9tonnants carnets de Maria Valtorta qui retranscrivent de mani\u00e8re unique la vie de J\u00e9sus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Facebook bloque l\u2019article que tu veux partagerTwitter le supprimeGoogle le dissimuleYoutube l\u2019interditAlors, le moment est venu de quitter les lieux&#8230; Quand la libert\u00e9 dispara\u00eet, que le voile des dictatures se l\u00e8ve, que les masques s&#8217;abaissent laconiquement devant les yeux rest\u00e9s ouverts, la meilleure chose \u00e0 faire est de quitter les lieux. J&#8217;avais pass\u00e9 quelques d\u00e9cennies [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[126],"tags":[],"class_list":["post-698","post","type-post","status-publish","format-standard","hentry","category-actus"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.arnwald.ovh\/en\/wp-json\/wp\/v2\/posts\/698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arnwald.ovh\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arnwald.ovh\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arnwald.ovh\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arnwald.ovh\/en\/wp-json\/wp\/v2\/comments?post=698"}],"version-history":[{"count":23,"href":"https:\/\/www.arnwald.ovh\/en\/wp-json\/wp\/v2\/posts\/698\/revisions"}],"predecessor-version":[{"id":909,"href":"https:\/\/www.arnwald.ovh\/en\/wp-json\/wp\/v2\/posts\/698\/revisions\/909"}],"wp:attachment":[{"href":"https:\/\/www.arnwald.ovh\/en\/wp-json\/wp\/v2\/media?parent=698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arnwald.ovh\/en\/wp-json\/wp\/v2\/categories?post=698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arnwald.ovh\/en\/wp-json\/wp\/v2\/tags?post=698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}